{"id":620,"date":"2023-01-24T17:29:12","date_gmt":"2023-01-24T17:29:12","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/algemeen-klassement-2\/"},"modified":"2026-05-13T15:40:14","modified_gmt":"2026-05-13T13:40:14","slug":"classificacao-geral-2","status":"publish","type":"product","link":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/retro-wielershirt\/algemeen-klassement-2\/","title":{"rendered":"SEB MTB MARATONS \u2013 CLASSIFICA\u00c7\u00c3O GERAL"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":284,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-620","product","type-product","status-publish","has-post-thumbnail","product_cat-leiderstruien","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEB MTB MARATONS - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEB MTB MARATONS - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:40:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA45289.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/\",\"name\":\"SEB MTB MARATONS - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.ton-merckx-wielershirts.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45289.jpg\",\"datePublished\":\"2023-01-24T17:29:12+00:00\",\"dateModified\":\"2026-05-13T13:40:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.ton-merckx-wielershirts.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45289.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.ton-merckx-wielershirts.nl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45289.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-cycling-jersey\\\/general-classification-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SEB MTB MARATONS &#8211; ALGEMEEN KLASSEMENT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.ton-merckx-wielershirts.nl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.ton-merckx-wielershirts.nl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEB MTB MARATONS - CLASSIFICA\u00c7\u00c3O GERAL - Ton Merckx Cycling Jerseys - Passeio pelo mundo das camisas de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/","og_locale":"pt_PT","og_type":"article","og_title":"SEB MTB MARATONS - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:40:14+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA45289.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/","url":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/","name":"SEB MTB MARATONS - CLASSIFICA\u00c7\u00c3O GERAL - Ton Merckx Cycling Jerseys - Passeio pelo mundo das camisas de ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.ton-merckx-wielershirts.nl\/wp-content\/uploads\/2023\/01\/SSA45289.jpg","datePublished":"2023-01-24T17:29:12+00:00","dateModified":"2026-05-13T13:40:14+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/#primaryimage","url":"https:\/\/mail.ton-merckx-wielershirts.nl\/wp-content\/uploads\/2023\/01\/SSA45289.jpg","contentUrl":"https:\/\/mail.ton-merckx-wielershirts.nl\/wp-content\/uploads\/2023\/01\/SSA45289.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/en\/retro-cycling-jersey\/general-classification-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"SEB MTB MARATONS &#8211; ALGEMEEN KLASSEMENT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","description":"milhares de camisas de ciclismo originais - encomende a sua r\u00e9plica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.ton-merckx-wielershirts.nl\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.ton-merckx-wielershirts.nl\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/product\/620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/media\/284"}],"wp:attachment":[{"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/media?parent=620"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/product_brand?post=620"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/product_cat?post=620"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.ton-merckx-wielershirts.nl\/pt\/wp-json\/wp\/v2\/product_tag?post=620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}